{"id":7145,"date":"2016-03-10T12:36:50","date_gmt":"2016-03-10T10:36:50","guid":{"rendered":"https:\/\/www.hostingvirtuale.com\/blog\/?p=7145"},"modified":"2016-11-07T13:34:47","modified_gmt":"2016-11-07T11:34:47","slug":"il-momento-migliore-per-pubblicare-sui-social-network","status":"publish","type":"post","link":"https:\/\/www.hostingvirtuale.com\/blog\/il-momento-migliore-per-pubblicare-sui-social-network-7145.html","title":{"rendered":"Il momento migliore per pubblicare sui social network"},"content":{"rendered":"<p><img decoding=\"async\" class=\"aligncenter size-full wp-image-7149\" src=\"https:\/\/www.hostingvirtuale.com\/blog\/wp-content\/uploads\/quando-pubblicare-social.jpg\" alt=\"Il momento migliore per pubblicare sui social network\" width=\"540\" height=\"300\" srcset=\"https:\/\/www.hostingvirtuale.com\/blog\/wp-content\/uploads\/quando-pubblicare-social.jpg 540w, https:\/\/www.hostingvirtuale.com\/blog\/wp-content\/uploads\/quando-pubblicare-social-300x167.jpg 300w\" sizes=\"(max-width: 540px) 100vw, 540px\" \/><\/p>\n<p>Partendo dal presupposto che tutto ci\u00f2 che sta alla base del <strong>social media marketing<\/strong> e la gestione delle community online fa parte del cappello delle scienze sociali e che non esiste nessuna formula matematica che governa le abitudini e i comportamenti di qualsiasi essere umano.<!--more--><\/p>\n<p>Se aggiungiamo i frequenti aggiornamenti degli algoritmi di ranking e di visualizzazione dei contenuti, quelli presenti in questo articolo sono i dati provenienti da statistiche e da best practice per la gestione dei profili social.<\/p>\n<div class=\"su-note\"  style=\"border-color:#e2dec9;border-radius:5px;-moz-border-radius:5px;-webkit-border-radius:5px;\"><div class=\"su-note-inner su-u-clearfix su-u-trim\" style=\"background-color:#FCF8E3;border-color:#ffffff;color:#000000;border-radius:5px;-moz-border-radius:5px;-webkit-border-radius:5px;\"><strong>Promo<\/strong>: Registra ora il tuo <a href=\"https:\/\/www.hostingvirtuale.com\/registrazione-dominio.php?tld=it&amp;utm_source=blog&amp;utm_medium=link&amp;utm_campaign=HostingVirtuale\" target=\"_blank\">dominio .it<\/a>!\u00a0Il servizio di gestione DNS \u00e8 gratuito e quindi sempre compreso nella registrazione di tutti i domini.<\/div><\/div>\n<h2>Miglior giorno e orario per pubblicare sui social<\/h2>\n<p>Dopo la giusta premessa, andiamo ad analizzare quali sono <strong>i giorni e gli orari migliori<\/strong> per raggiungere il proprio pubblico online. Queste informazioni sono importanti per chi vuole fare business online, poich\u00e9, proprio come nella vita reale, il tempismo \u00e8 tutto: conoscere gli orari di apertura \u00e8 fondamentale, cos\u00ec come essere a conoscenza delle abitudini del proprio pubblico.<\/p>\n<p><a href=\"https:\/\/www.hostingvirtuale.com\/blog\/cosa-pubblicare-sulla-pagina-facebook-di-una-pmi-6532.html\" target=\"_blank\"><img decoding=\"async\" class=\"alignleft size-medium wp-image-6536\" src=\"https:\/\/www.hostingvirtuale.com\/blog\/wp-content\/uploads\/facebook-pmi-300x167.jpg\" alt=\"Cosa pubblicare sulla pagina Facebook di una PMI\" width=\"300\" height=\"167\" srcset=\"https:\/\/www.hostingvirtuale.com\/blog\/wp-content\/uploads\/facebook-pmi-300x167.jpg 300w, https:\/\/www.hostingvirtuale.com\/blog\/wp-content\/uploads\/facebook-pmi.jpg 540w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>Assumere che tutto il pubblico possa vedere un contenuto appena esso sar\u00e0 pubblicato \u00e8 uno degli errori pi\u00f9 grandi e pi\u00f9 comuni per chi si occupa di social media marketing.<\/p>\n<p>Il post su Facebook pu\u00f2 essere sepolto tra tutti gli aggiornamenti quotidiani, soprattutto se pubblicato nelle ora di punta e nei momenti di picco.<\/p>\n<p>Per comprendere meglio quale sar\u00e0 <strong>il momento migliore per pubblicare su Facebook<\/strong>, Twitter e altri canali social \u00e8 necessario determinare, per ogni piattaforma, le abitudini del proprio pubblico.<\/p>\n<p>Target adolescente o senior pu\u00f2 essere un fattore che metter\u00e0 in risalto abitudini di accesso differenti, cos\u00ec come il fuso orario soprattutto se il proprio target \u00e8 oltreoceano.<\/p>\n<p>Trovando il giorno e l&#8217;orario giusti aumenter\u00e0 la probabilit\u00e0 di intercettare il proprio pubblico di riferimento. In questa infografica \u00e8 possibile vedere i risultati della ricerca condotta da <a href=\"http:\/\/www.wssmarketing.com\/\" target=\"_blank\" rel=\"nofollow\">What She Said Marketing Solutions<\/a>\u00a0in relazione ai momenti migliori e quelli peggiori per <strong>pubblicare sui social media<\/strong>.<\/p>\n<p>Gli orari indicati da queste statistiche sono basati su abitudini anglofone.<\/p>\n<h2>Infografica: quando pubblicare su Facebook, Twitter, Pinterest e LinkedIn<\/h2>\n<p><a href=\"https:\/\/www.hostingvirtuale.com\/blog\/infografiche\/quando-pubblicare-social.html\"><img decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/www.hostingvirtuale.com\/blog\/infografiche\/quando-pubblicare-social.png\" alt=\"Quando pubblicare sui social network\" width=\"640\" height=\"1811\" \/><\/a><\/p>\n<h3><strong>Facebook<\/strong><\/h3>\n<p>Con 1,5 miliardi di utenti attivi, Facebook \u00e8 la pi\u00f9 grande community di utenti iscritti ad un social network.<\/p>\n<p><strong>Orario migliore<\/strong>: dalle 13:00 alle 16:00<\/p>\n<p><strong>Giorno migliore<\/strong>: mercoled\u00ec alle 15:00<\/p>\n<p><strong>Momento peggiore<\/strong>: prima delle 8:00, dopo le 20:00 e nei weekend<\/p>\n<p>Il pomeriggio \u00e8 il momento migliore per pubblicare su Facebook poich\u00e9 molte persone iniziano a rallentare i propri ritmi lavorativi e iniziano a controllare i profili social.<\/p>\n<h3><strong>Twitter<\/strong><\/h3>\n<p><img decoding=\"async\" class=\"alignleft size-medium wp-image-6991\" src=\"https:\/\/www.hostingvirtuale.com\/blog\/wp-content\/uploads\/usare-twitter-hotel-300x167.jpg\" alt=\"Come sfruttare Twitter al meglio per hotel e strutture turistiche\" width=\"300\" height=\"167\" srcset=\"https:\/\/www.hostingvirtuale.com\/blog\/wp-content\/uploads\/usare-twitter-hotel-300x167.jpg 300w, https:\/\/www.hostingvirtuale.com\/blog\/wp-content\/uploads\/usare-twitter-hotel.jpg 540w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>La velocit\u00e0 di questo media ha un audience di 316 milioni di utenti attivi distribuiti maggiormente sulla fascia 18-24 anni.<\/p>\n<p><strong>Orario migliore<\/strong>: dal luned\u00ec al gioved\u00ec dalle 9:00 alle 15:00<\/p>\n<p><strong>Picco di attenzione<\/strong>: dalle 13:00 alle 15:00<\/p>\n<p><strong>Momento peggiore<\/strong>: dopo le 20:00 e il venerd\u00ec dopo le 15:00<\/p>\n<div class=\"su-note\"  style=\"border-color:#dce2e4;border-radius:5px;-moz-border-radius:5px;-webkit-border-radius:5px;\"><div class=\"su-note-inner su-u-clearfix su-u-trim\" style=\"background-color:#F6FCFE;border-color:#ffffff;color:#000000;border-radius:5px;-moz-border-radius:5px;-webkit-border-radius:5px;\"><strong>Per approfondire<\/strong>:\u00a0<a href=\"https:\/\/www.hostingvirtuale.com\/blog\/come-perche-usare-twitter-per-pmi-6228.html\" target=\"_blank\">Come e perch\u00e9 usare Twitter per le PMI<\/a><\/div><\/div>\n<h3><strong>Instagram<\/strong><\/h3>\n<p>Con la sua app per la condivisione di foto e video, Instagram ha una base di utenti attivi pari a 400 milioni, di cui il 55% \u00e8 nella fascia 18-29 anni<\/p>\n<p><strong>Fasce migliori<\/strong>: 14:00-15:00 e 20:00-21:00<\/p>\n<p><strong>Giorni migliori<\/strong>: luned\u00ec e mercoled\u00ec<\/p>\n<p><strong>Momento peggiore<\/strong>: dalle 15:00 alle 16:00 e la domenica<\/p>\n<h3><strong>Google+<\/strong><\/h3>\n<p>La popolarit\u00e0 dell&#8217;interconnessione dei prodotti Google ha fatto incrementare l&#8217;accesso a Google+: 300 milioni di utenti attivi.<\/p>\n<p><strong>Orario migliore<\/strong>: le mattine dalle 9:00 alle 10:00<\/p>\n<p><strong>Giorno migliore<\/strong>: alle 9:00 del mercoled\u00ec<\/p>\n<p><strong>Momento peggiore<\/strong>: prima delle 9:00 e la sera dopo cena<\/p>\n<h3><strong>LinkedIn<\/strong><\/h3>\n<p>Ci sono attualmente circa 380 milioni di utenti totali su LinkedIn, social media basato su connessioni legate alla professione.<\/p>\n<p><strong>Orario migliore<\/strong>: dal marted\u00ec al gioved\u00ec dalle 17:00 alle 18:00<\/p>\n<p><strong>Momento peggiore<\/strong>: la domenica e dalle 22:00 alle 6:00 del mattino<\/p>\n<h3><strong>Pinterest<\/strong><\/h3>\n<p>Pinterest \u00e8 un social media basato sulla comunicazione visuale: 72,8 milioni di utenti, di cui 71% pubblico femminile.<\/p>\n<p><strong>Periodo migliore<\/strong>: nei weekend, sebbene l&#8217;engagement \u00e8 pi\u00f9 alto dalle 20:00 alle 23:00<\/p>\n<p><strong>Momento peggiore<\/strong>: negli orari lavorativi<\/p>\n<h2>Scegli il momento giusto per postare e analizza<\/h2>\n<p>Infine ricordiamo che i dati e gli <a href=\"https:\/\/www.hostingvirtuale.com\/blog\/insight-analizzare-monitorare-pagina-facebook-4150.html\" target=\"_blank\">strumenti di Insight e analytics<\/a>, aiutano i <strong>social media manager<\/strong> a personalizzare queste statistiche calibrandole nella propria realt\u00e0 e di trovare i giorni e gli orari migliori, che possono anche essere del tutto diversi da quelli proposti in questo articolo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Partendo dal presupposto che tutto ci\u00f2 che sta alla base del social media marketing e la gestione delle community online fa parte del cappello delle scienze sociali e che non esiste nessuna formula matematica che governa le abitudini e i comportamenti di qualsiasi essere umano.<\/p>\n","protected":false},"author":5,"featured_media":7149,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":{"twitter_97753652_97753652":""},"rop_publish_now_history":[],"rop_publish_now_status":"pending","_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","footnotes":""},"categories":[453],"tags":[15,455,536,527,16],"class_list":{"0":"post-7145","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-social-media","8":"tag-facebook","9":"tag-infografica","10":"tag-linkedin","11":"tag-pinterest","12":"tag-twitter","13":"entry"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Il momento migliore per pubblicare sui social network<\/title>\n<meta name=\"description\" content=\"Quali sono\u00a0i giorni e gli orari migliori\u00a0per raggiungere il proprio pubblico online e quindi pubblicare un post su Facebook, Twitter, Pinterest e LinkedIn.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.hostingvirtuale.com\/blog\/il-momento-migliore-per-pubblicare-sui-social-network-7145.html\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Il momento migliore per pubblicare sui social network\" \/>\n<meta property=\"og:description\" content=\"Quali sono\u00a0i giorni e gli orari migliori\u00a0per raggiungere il proprio pubblico online e quindi pubblicare un post su Facebook, Twitter, Pinterest e LinkedIn.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.hostingvirtuale.com\/blog\/il-momento-migliore-per-pubblicare-sui-social-network-7145.html\" \/>\n<meta property=\"og:site_name\" content=\"Il blog di HostingVirtuale\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/HostingVirtuale\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/nicocarmigna\" \/>\n<meta property=\"article:published_time\" content=\"2016-03-10T10:36:50+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-11-07T11:34:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.hostingvirtuale.com\/blog\/wp-content\/uploads\/quando-pubblicare-social.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"540\" \/>\n\t<meta property=\"og:image:height\" content=\"300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Nicola Carmignani\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@nicocarmigna\" \/>\n<meta name=\"twitter:site\" content=\"@HostingVirtuale\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Nicola Carmignani\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.hostingvirtuale.com\/blog\/il-momento-migliore-per-pubblicare-sui-social-network-7145.html\",\"url\":\"https:\/\/www.hostingvirtuale.com\/blog\/il-momento-migliore-per-pubblicare-sui-social-network-7145.html\",\"name\":\"Il momento migliore per pubblicare sui social network\",\"isPartOf\":{\"@id\":\"https:\/\/www.hostingvirtuale.com\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.hostingvirtuale.com\/blog\/il-momento-migliore-per-pubblicare-sui-social-network-7145.html#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.hostingvirtuale.com\/blog\/il-momento-migliore-per-pubblicare-sui-social-network-7145.html#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.hostingvirtuale.com\/blog\/wp-content\/uploads\/quando-pubblicare-social.jpg\",\"datePublished\":\"2016-03-10T10:36:50+00:00\",\"dateModified\":\"2016-11-07T11:34:47+00:00\",\"author\":{\"@id\":\"https:\/\/www.hostingvirtuale.com\/blog\/#\/schema\/person\/48402fc19de178d4bd5f709d3e86adfe\"},\"description\":\"Quali sono\u00a0i giorni e gli orari migliori\u00a0per raggiungere il proprio pubblico online e quindi pubblicare un post su Facebook, Twitter, Pinterest e LinkedIn.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.hostingvirtuale.com\/blog\/il-momento-migliore-per-pubblicare-sui-social-network-7145.html#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.hostingvirtuale.com\/blog\/il-momento-migliore-per-pubblicare-sui-social-network-7145.html\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.hostingvirtuale.com\/blog\/il-momento-migliore-per-pubblicare-sui-social-network-7145.html#primaryimage\",\"url\":\"https:\/\/www.hostingvirtuale.com\/blog\/wp-content\/uploads\/quando-pubblicare-social.jpg\",\"contentUrl\":\"https:\/\/www.hostingvirtuale.com\/blog\/wp-content\/uploads\/quando-pubblicare-social.jpg\",\"width\":540,\"height\":300,\"caption\":\"Il momento migliore per pubblicare sui social network\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.hostingvirtuale.com\/blog\/il-momento-migliore-per-pubblicare-sui-social-network-7145.html#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.hostingvirtuale.com\/blog\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Il momento migliore per pubblicare sui social network\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.hostingvirtuale.com\/blog\/#website\",\"url\":\"https:\/\/www.hostingvirtuale.com\/blog\/\",\"name\":\"Il blog di HostingVirtuale\",\"description\":\"Hosting e Registrazione Domini\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.hostingvirtuale.com\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.hostingvirtuale.com\/blog\/#\/schema\/person\/48402fc19de178d4bd5f709d3e86adfe\",\"name\":\"Nicola Carmignani\",\"sameAs\":[\"http:\/\/www.nicolacarmignani.it\/\",\"https:\/\/www.facebook.com\/nicocarmigna\",\"https:\/\/x.com\/nicocarmigna\"],\"url\":\"https:\/\/www.hostingvirtuale.com\/blog\/author\/nicola\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Il momento migliore per pubblicare sui social network","description":"Quali sono\u00a0i giorni e gli orari migliori\u00a0per raggiungere il proprio pubblico online e quindi pubblicare un post su Facebook, Twitter, Pinterest e LinkedIn.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.hostingvirtuale.com\/blog\/il-momento-migliore-per-pubblicare-sui-social-network-7145.html","og_locale":"it_IT","og_type":"article","og_title":"Il momento migliore per pubblicare sui social network","og_description":"Quali sono\u00a0i giorni e gli orari migliori\u00a0per raggiungere il proprio pubblico online e quindi pubblicare un post su Facebook, Twitter, Pinterest e LinkedIn.","og_url":"https:\/\/www.hostingvirtuale.com\/blog\/il-momento-migliore-per-pubblicare-sui-social-network-7145.html","og_site_name":"Il blog di HostingVirtuale","article_publisher":"https:\/\/www.facebook.com\/HostingVirtuale","article_author":"https:\/\/www.facebook.com\/nicocarmigna","article_published_time":"2016-03-10T10:36:50+00:00","article_modified_time":"2016-11-07T11:34:47+00:00","og_image":[{"width":540,"height":300,"url":"https:\/\/www.hostingvirtuale.com\/blog\/wp-content\/uploads\/quando-pubblicare-social.jpg","type":"image\/jpeg"}],"author":"Nicola Carmignani","twitter_card":"summary_large_image","twitter_creator":"@nicocarmigna","twitter_site":"@HostingVirtuale","twitter_misc":{"Scritto da":"Nicola Carmignani","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.hostingvirtuale.com\/blog\/il-momento-migliore-per-pubblicare-sui-social-network-7145.html","url":"https:\/\/www.hostingvirtuale.com\/blog\/il-momento-migliore-per-pubblicare-sui-social-network-7145.html","name":"Il momento migliore per pubblicare sui social network","isPartOf":{"@id":"https:\/\/www.hostingvirtuale.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.hostingvirtuale.com\/blog\/il-momento-migliore-per-pubblicare-sui-social-network-7145.html#primaryimage"},"image":{"@id":"https:\/\/www.hostingvirtuale.com\/blog\/il-momento-migliore-per-pubblicare-sui-social-network-7145.html#primaryimage"},"thumbnailUrl":"https:\/\/www.hostingvirtuale.com\/blog\/wp-content\/uploads\/quando-pubblicare-social.jpg","datePublished":"2016-03-10T10:36:50+00:00","dateModified":"2016-11-07T11:34:47+00:00","author":{"@id":"https:\/\/www.hostingvirtuale.com\/blog\/#\/schema\/person\/48402fc19de178d4bd5f709d3e86adfe"},"description":"Quali sono\u00a0i giorni e gli orari migliori\u00a0per raggiungere il proprio pubblico online e quindi pubblicare un post su Facebook, Twitter, Pinterest e LinkedIn.","breadcrumb":{"@id":"https:\/\/www.hostingvirtuale.com\/blog\/il-momento-migliore-per-pubblicare-sui-social-network-7145.html#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.hostingvirtuale.com\/blog\/il-momento-migliore-per-pubblicare-sui-social-network-7145.html"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.hostingvirtuale.com\/blog\/il-momento-migliore-per-pubblicare-sui-social-network-7145.html#primaryimage","url":"https:\/\/www.hostingvirtuale.com\/blog\/wp-content\/uploads\/quando-pubblicare-social.jpg","contentUrl":"https:\/\/www.hostingvirtuale.com\/blog\/wp-content\/uploads\/quando-pubblicare-social.jpg","width":540,"height":300,"caption":"Il momento migliore per pubblicare sui social network"},{"@type":"BreadcrumbList","@id":"https:\/\/www.hostingvirtuale.com\/blog\/il-momento-migliore-per-pubblicare-sui-social-network-7145.html#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.hostingvirtuale.com\/blog"},{"@type":"ListItem","position":2,"name":"Il momento migliore per pubblicare sui social network"}]},{"@type":"WebSite","@id":"https:\/\/www.hostingvirtuale.com\/blog\/#website","url":"https:\/\/www.hostingvirtuale.com\/blog\/","name":"Il blog di HostingVirtuale","description":"Hosting e Registrazione Domini","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.hostingvirtuale.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.hostingvirtuale.com\/blog\/#\/schema\/person\/48402fc19de178d4bd5f709d3e86adfe","name":"Nicola Carmignani","sameAs":["http:\/\/www.nicolacarmignani.it\/","https:\/\/www.facebook.com\/nicocarmigna","https:\/\/x.com\/nicocarmigna"],"url":"https:\/\/www.hostingvirtuale.com\/blog\/author\/nicola"}]}},"_links":{"self":[{"href":"https:\/\/www.hostingvirtuale.com\/blog\/wp-json\/wp\/v2\/posts\/7145","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hostingvirtuale.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.hostingvirtuale.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.hostingvirtuale.com\/blog\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hostingvirtuale.com\/blog\/wp-json\/wp\/v2\/comments?post=7145"}],"version-history":[{"count":0,"href":"https:\/\/www.hostingvirtuale.com\/blog\/wp-json\/wp\/v2\/posts\/7145\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.hostingvirtuale.com\/blog\/wp-json\/wp\/v2\/media\/7149"}],"wp:attachment":[{"href":"https:\/\/www.hostingvirtuale.com\/blog\/wp-json\/wp\/v2\/media?parent=7145"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.hostingvirtuale.com\/blog\/wp-json\/wp\/v2\/categories?post=7145"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.hostingvirtuale.com\/blog\/wp-json\/wp\/v2\/tags?post=7145"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}